{"id":69040,"date":"2026-05-12T17:07:51","date_gmt":"2026-05-12T15:07:51","guid":{"rendered":"https:\/\/isarta.fr\/infos\/?p=69040"},"modified":"2026-05-13T17:51:36","modified_gmt":"2026-05-13T15:51:36","slug":"reconnaissance-osez-poser-cette-question-surprenante-en-entrevue","status":"publish","type":"post","link":"https:\/\/isarta.fr\/infos\/reconnaissance-osez-poser-cette-question-surprenante-en-entrevue\/","title":{"rendered":"Reconnaissance : Osez poser cette question surprenante en entrevue"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/isarta.com\/infos\/wp-content\/uploads\/2026\/05\/Jean-Pierre-BRUN-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-111804\"\/><figcaption class=\"wp-element-caption\"><em>Jean-Pierre Brun, consultant RH pour le cabinet Empreinte humaine et professeur \u00e9m\u00e9rite \u00e0 l&rsquo;Universit\u00e9 Laval (source : courtoisie)<\/em><\/figcaption><\/figure>\n<p>12 mai 2026<\/p>\n<p class=\"has-medium-font-size\"><strong>Quand Jean-Pierre Brun fait passer une entrevue d&#8217;embauche dans son cabinet de consulting RH, Empreinte humaine, il pose toujours la question suivante : \u00ab Si vous venez travailler chez nous, comment voulez-vous \u00eatre reconnus? \u00bb Si la question surprend certains candidats, elle semble malgr\u00e9 tout couler de source, quand on conna\u00eet le parcours de ce sp\u00e9cialiste de la reconnaissance au travail. Interview.  <\/strong><\/p>\n<p><strong>Pourquoi posez-vous cette question ? <\/strong><\/p>\n<p><strong>Jean-Pierre brun :<\/strong> La reconnaissance, c&rsquo;est propre \u00e0 chacun. Certaines personnes aiment les remerciements publics, d&rsquo;autres non. Certaines veulent se faire reconna\u00eetre pour leurs accomplissements, d&rsquo;autres pour leurs qualit\u00e9s personnelles. En posant directement la question \u00e0 ses employ\u00e9s, on peut ajuster son approche de gestion.<\/p>\n<p><strong>Comment abordez-vous le sujet ? Comprennent-ils la question du premier coup?<\/strong><\/p>\n<p><strong>J-P B:<\/strong> La plupart du temps, ils sont surpris et ne savent pas quoi r\u00e9pondre. Ils me demandent parfois quelques minutes de r\u00e9flexion. Ce n&rsquo;est pas une question \u00e0 laquelle on r\u00e9fl\u00e9chit tous les jours. J&rsquo;en profite pour leur expliquer davantage le concept. Je leur demande ce qui est important pour eux, en mati\u00e8re de reconnaissance, pour se sentir motiv\u00e9 au travail. <\/p>\n<p>Il y a des gens qui, par exemple, trouvent important d&rsquo;avoir acc\u00e8s \u00e0 du soutien de leur manager. Ils veulent sentir que, dans le feu de l&rsquo;action, s&rsquo;ils ont un doute, le manager sera l\u00e0 pour les \u00e9pauler. D&rsquo;autres veulent \u00eatre inform\u00e9s de comment \u00e9volue l&rsquo;entreprise, ils veulent avoir de la visibilit\u00e9 sur les projets \u00e0 venir. <\/p>\n<p>S&rsquo;ils sont d\u00e9stabilis\u00e9s, je leur donne des exemples de forme de reconnaissance.<\/p>\n<p><strong>Le concept de reconnaissance semble tr\u00e8s large finalement ? <\/strong><\/p>\n<p><strong>J-P B:<\/strong> Au travail, je vois deux besoins distincts. <\/p>\n<ul>\n<li>Il y a un besoin de reconnaissance de base qui rel\u00e8ve de la politesse. C&rsquo;est ce que j&rsquo;appelle la reconnaissance de gratitude. Tous les bravos, les mercis, les &lsquo;good job&rsquo; \u00e9chang\u00e9s entre coll\u00e8gues. <\/li>\n<\/ul>\n<ul>\n<li>Puis il y a un besoin plus fondamental qu&rsquo;on appelle la consid\u00e9ration. Les employ\u00e9s veulent se sentir des citoyens organisationnels. Ils veulent \u00eatre inform\u00e9s, consult\u00e9s et sentir qu&rsquo;ils ont leur mot \u00e0 dire. &nbsp;<\/li>\n<\/ul>\n<p><strong>\u00c7a doit donner des conversations int\u00e9ressantes avec les candidats<\/strong>!<\/p>\n<p><strong>J-P B:<\/strong> En effet. Souvent, en fin d&rsquo;entrevue, ils reviennent sur la question et me disent combien ils l&rsquo;ont trouv\u00e9e int\u00e9ressante. Ce n&rsquo;est pas une r\u00e9flexion naturelle qu&rsquo;on a tous les jours.<\/p>\n<p><strong>Que faites-vous de cette information ? Est-il vraiment possible pour un manager de personnaliser son approche de reconnaissance pour chaque employ\u00e9 ?<\/strong><\/p>\n<p><strong>J-P B:<\/strong> Bien s\u00fbr, il faut trouver un \u00e9quilibre. Si on a 40 employ\u00e9s, \u00e7a ne signifie pas qu&rsquo;on a 40 profils diff\u00e9rents. Il y a des choses qui sont communes et des \u00e9l\u00e9ments distinctifs. <\/p>\n<p>Le r\u00f4le d&rsquo;un manager, c&rsquo;est de bien conna\u00eetre son \u00e9quipe, pour savoir o\u00f9 sont les leviers de ses employ\u00e9s. Un peu comme un coach de hockey, il ne g\u00e8re pas chaque joueur de la m\u00eame mani\u00e8re. Il adapte sa gestion en fonction du joueur.<\/p>\n<p><strong>Selon les plus r\u00e9cents sondages, la reconnaissance semble \u00eatre en berne dans les entreprises. Seuls 34% des conseillers RH se sentent appr\u00e9ci\u00e9s (<strong>Achievers Workforce Institute, 2025<\/strong>). Faites-vous cette m\u00eame observation sur le terrain? <\/strong><\/p>\n<p><strong>J-P B:<\/strong> Je m&rsquo;int\u00e9resse \u00e0 la question depuis 25 ans et, effectivement, le besoin de reconnaissance semble \u00eatre plus important aujourd&rsquo;hui que jamais. Je vois une augmentation du d\u00e9sir d&rsquo;\u00eatre reconnu, \u00e0 la fois de mani\u00e8re informelle, mais aussi de mani\u00e8re plus formelle, voire sous l&rsquo;angle de la r\u00e9mun\u00e9ration, surtout dans le contexte de la crise \u00e9conomique.<\/p>\n<p>Les gens ne veulent pas juste des mercis, des bravos ou des f\u00e9licitations. Ils veulent que la reconnaissance se manifeste par des gestes financiers concrets. Ce n&rsquo;est pas la seule demande, loin de l\u00e0, mais c&rsquo;est un \u00e9l\u00e9ment important.<\/p>\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n<div class=\" content_cards_card content_cards_domain_formations-isarta-fr\">\n<div class=\"content_cards_image\">\n\t\t\t\t<a class=\"content_cards_image_link\" href=\"https:\/\/formations.isarta.fr\/cours\/le-bien-etre-au-travail-le-bonheur-des-employes\/40?utm_source=Isarta_Infos\" target=\"_blank\"><br \/>\n\t\t\t\t\t<img src=\"https:\/\/formations.isarta.com\/assets\/images\/30\/30ef2a_BienEtreAuTravail_crop_1077x606.jpeg\" alt=\"Formation webinaire: Le bien-\u00eatre au travail - Le bonheur des employ\u00e9s\">\t\t\t\t<\/a>\n\t\t<\/div>\n<div class=\"content_cards_title\">\n\t\t<a class=\"content_cards_title_link\" href=\"https:\/\/formations.isarta.fr\/cours\/le-bien-etre-au-travail-le-bonheur-des-employes\/40?utm_source=Isarta_Infos\" target=\"_blank\"><br \/>\n\t\t\tFormation webinaire: Le bien-\u00eatre au travail &#8211; Le bonheur des employ\u00e9s\t\t<\/a>\n\t<\/div>\n<div class=\"content_cards_description\">\n\t\t<a class=\"content_cards_description_link\" href=\"https:\/\/formations.isarta.fr\/cours\/le-bien-etre-au-travail-le-bonheur-des-employes\/40?utm_source=Isarta_Infos\" target=\"_blank\"><\/p>\n<p>Le bien-\u00eatre au travail &#8211; Le bonheur des employ\u00e9s. Comprenez le r\u00f4le strat\u00e9gique du CHO et mettez en place une d\u00e9marche bien-\u00eatre : diagnostic, barom\u00e8tre, atelier et plan d\u2019action<\/p>\n<p>\t\t<\/a>\n\t<\/div>\n<div class=\"content_cards_site_name\">\n\t\t<img src=\"https:\/\/formations.isarta.fr\/icons\/favicon-16x16.png\" alt=\"formations.isarta.fr\" class=\"content_cards_favicon\"\/>\t\tformations.isarta.fr\t<\/div>\n<\/div>\n<div class=\" content_cards_card content_cards_domain_formations-isarta-fr\">\n<div class=\"content_cards_image\">\n\t\t\t\t<a class=\"content_cards_image_link\" href=\"https:\/\/formations.isarta.fr\/cours\/remuneration-flexibilite-et-parcours-les-piliers-de-votre-proposition-de-valeur-en-pme\/87?utm_source=Isarta_Infos\" target=\"_blank\"><br \/>\n\t\t\t\t\t<img src=\"https:\/\/formations.isarta.com\/assets\/images\/1f\/1f94a9_R-mun-ration-globale.jpg\" alt=\"Formation webinaire: R\u00e9mun\u00e9ration, flexibilit\u00e9 et parcours : les piliers de votre proposition de valeur en PME\">\t\t\t\t<\/a>\n\t\t<\/div>\n<div class=\"content_cards_title\">\n\t\t<a class=\"content_cards_title_link\" href=\"https:\/\/formations.isarta.fr\/cours\/remuneration-flexibilite-et-parcours-les-piliers-de-votre-proposition-de-valeur-en-pme\/87?utm_source=Isarta_Infos\" target=\"_blank\"><br \/>\n\t\t\tFormation webinaire: R\u00e9mun\u00e9ration, flexibilit\u00e9 et parcours : les piliers de votre proposition de valeur en PME\t\t<\/a>\n\t<\/div>\n<div class=\"content_cards_description\">\n\t\t<a class=\"content_cards_description_link\" href=\"https:\/\/formations.isarta.fr\/cours\/remuneration-flexibilite-et-parcours-les-piliers-de-votre-proposition-de-valeur-en-pme\/87?utm_source=Isarta_Infos\" target=\"_blank\"><\/p>\n<p>R\u00e9mun\u00e9ration, flexibilit\u00e9 et parcours : les piliers de votre proposition de valeur en PME. Mettez en valeur les points strat\u00e9giques de r\u00e9mun\u00e9ration globale pour attirer et fid\u00e9liser efficacement les talents dans votre organisation<\/p>\n<p>\t\t<\/a>\n\t<\/div>\n<div class=\"content_cards_site_name\">\n\t\t<img src=\"https:\/\/formations.isarta.fr\/icons\/favicon-16x16.png\" alt=\"formations.isarta.fr\" class=\"content_cards_favicon\"\/>\t\tformations.isarta.fr\t<\/div>\n<\/div>\n<div class=\" content_cards_card content_cards_domain_formations-isarta-fr\">\n<div class=\"content_cards_image\">\n\t\t\t\t<a class=\"content_cards_image_link\" href=\"https:\/\/formations.isarta.fr\/cours\/intelligence-emotionnelle-art-de-la-persuasion\/4?utm_source=Isarta_Infos\" target=\"_blank\"><br \/>\n\t\t\t\t\t<img src=\"https:\/\/formations.isarta.com\/assets\/images\/f9\/f955de_Art-persuasion-NEW.jpg\" alt=\"Formation webinaire: Intelligence \u00e9motionnelle &amp; Art de la persuasion - profils de personnalit\u00e9\">\t\t\t\t<\/a>\n\t\t<\/div>\n<div class=\"content_cards_title\">\n\t\t<a class=\"content_cards_title_link\" href=\"https:\/\/formations.isarta.fr\/cours\/intelligence-emotionnelle-art-de-la-persuasion\/4?utm_source=Isarta_Infos\" target=\"_blank\"><br \/>\n\t\t\tFormation webinaire: Intelligence \u00e9motionnelle &#038; Art de la persuasion &#8211; profils de personnalit\u00e9\t\t<\/a>\n\t<\/div>\n<div class=\"content_cards_description\">\n\t\t<a class=\"content_cards_description_link\" href=\"https:\/\/formations.isarta.fr\/cours\/intelligence-emotionnelle-art-de-la-persuasion\/4?utm_source=Isarta_Infos\" target=\"_blank\"><\/p>\n<p>Intelligence \u00e9motionnelle &amp; Art de la persuasion, profils de personnalit\u00e9. Comprendre les styles sociaux pour ainsi am\u00e9liorer vos diff\u00e9rents types de\u00a0relations interpersonnelles (clients, coll\u00e8gues, employ\u00e9s&#8230;)<\/p>\n<p>\t\t<\/a>\n\t<\/div>\n<div class=\"content_cards_site_name\">\n\t\t<img src=\"https:\/\/formations.isarta.fr\/icons\/favicon-16x16.png\" alt=\"formations.isarta.fr\" class=\"content_cards_favicon\"\/>\t\tformations.isarta.fr\t<\/div>\n<\/div>\n<div class=\" content_cards_card content_cards_domain_formations-isarta-fr\">\n<div class=\"content_cards_image\">\n\t\t\t\t<a class=\"content_cards_image_link\" href=\"https:\/\/formations.isarta.fr\/cours\/management-101-gestion-de-performance-delegation-et-feedback\/4?utm_source=Isarta_Infos\" target=\"_blank\"><br \/>\n\t\t\t\t\t<img src=\"https:\/\/formations.isarta.com\/assets\/images\/54\/54cf20_Management_crop_1989x1119.jpg\" alt=\"Formation webinaire: Management 101 : gestion de performance, d\u00e9l\u00e9gation et feedback - les 4 outils de base d\u2019un manager efficace\">\t\t\t\t<\/a>\n\t\t<\/div>\n<div class=\"content_cards_title\">\n\t\t<a class=\"content_cards_title_link\" href=\"https:\/\/formations.isarta.fr\/cours\/management-101-gestion-de-performance-delegation-et-feedback\/4?utm_source=Isarta_Infos\" target=\"_blank\"><br \/>\n\t\t\tFormation webinaire: Management 101 : gestion de performance, d\u00e9l\u00e9gation et feedback &#8211; les 4 outils de base d\u2019un manager efficace\t\t<\/a>\n\t<\/div>\n<div class=\"content_cards_description\">\n\t\t<a class=\"content_cards_description_link\" href=\"https:\/\/formations.isarta.fr\/cours\/management-101-gestion-de-performance-delegation-et-feedback\/4?utm_source=Isarta_Infos\" target=\"_blank\"><\/p>\n<p>Management 101 : gestion de performance, d\u00e9l\u00e9gation et feedback, les 4 outils de base d\u2019un manager efficace. Raffiner vos techniques pour tirer le meilleur de votre \u00e9quipe de travail. D\u00e9couvrez la trousse \u00e0 outils d\u2019un manager efficace<\/p>\n<p>\t\t<\/a>\n\t<\/div>\n<div class=\"content_cards_site_name\">\n\t\t<img src=\"https:\/\/formations.isarta.fr\/icons\/favicon-16x16.png\" alt=\"formations.isarta.fr\" class=\"content_cards_favicon\"\/>\t\tformations.isarta.fr\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Quand Jean-Pierre Brun fait passer une entrevue d&#8217;embauche dans son cabinet de consulting RH, Empreinte humaine, il pose toujours la question suivante : \u00ab Si vous venez travailler chez nous, comment voulez-vous \u00eatre reconnus? \u00bb Si la question surprend certains candidats, elle semble malgr\u00e9 tout couler de source, quand on conna\u00eet le parcours de ce sp\u00e9cialiste de la reconnaissance au travail. Interview<\/p>\n","protected":false},"author":64,"featured_media":69050,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[264,265,159],"tags":[],"_links":{"self":[{"href":"https:\/\/isarta.fr\/infos\/wp-json\/wp\/v2\/posts\/69040"}],"collection":[{"href":"https:\/\/isarta.fr\/infos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isarta.fr\/infos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isarta.fr\/infos\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/isarta.fr\/infos\/wp-json\/wp\/v2\/comments?post=69040"}],"version-history":[{"count":1,"href":"https:\/\/isarta.fr\/infos\/wp-json\/wp\/v2\/posts\/69040\/revisions"}],"predecessor-version":[{"id":69051,"href":"https:\/\/isarta.fr\/infos\/wp-json\/wp\/v2\/posts\/69040\/revisions\/69051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/isarta.fr\/infos\/wp-json\/wp\/v2\/media\/69050"}],"wp:attachment":[{"href":"https:\/\/isarta.fr\/infos\/wp-json\/wp\/v2\/media?parent=69040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isarta.fr\/infos\/wp-json\/wp\/v2\/categories?post=69040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isarta.fr\/infos\/wp-json\/wp\/v2\/tags?post=69040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}